{"id":11254,"date":"2021-10-26T15:26:37","date_gmt":"2021-10-26T15:26:37","guid":{"rendered":"https:\/\/www.rmff.org\/?p=11254"},"modified":"2022-03-09T21:29:08","modified_gmt":"2022-03-09T21:29:08","slug":"celebrating-thirty-five-years-of-impact","status":"publish","type":"post","link":"https:\/\/old.rmff.wrhosting.net\/it\/2021\/10\/celebrating-thirty-five-years-of-impact\/","title":{"rendered":"Celebrando trentacinque anni di impatto"},"content":{"rendered":"<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p>Nell&#039;ottobre 1986,&nbsp;<a href=\"https:\/\/www.rmff.org\/who-we-are\/history-about-richard-m-fairbanks\/\" target=\"_blank\" rel=\"noreferrer noopener\">Richard M. (&quot;Dick&quot;) Fairbanks<\/a>&nbsp;cre\u00f2 la sua omonima fondazione per aumentare la vitalit\u00e0 della sua citt\u00e0 natale di Indianapolis. Trentacinque anni dopo, la Fondazione Richard M. Fairbanks continua a farlo&nbsp;<a href=\"https:\/\/www.rmff.org\/our-work\/\" target=\"_blank\" rel=\"noreferrer noopener\">concentrare la nostra concessione di sovvenzioni<\/a>, ricerca e valutazione, collaborazioni e convegni intersettoriali a sostegno della nostra missione di promuovere la vitalit\u00e0 di Indianapolis e il benessere della sua gente. Dalla sua istituzione, la Fondazione ha assegnato pi\u00f9 di&nbsp;<a href=\"https:\/\/www.rmff.org\/grantmaking\/grants-awarded\/\" target=\"_blank\" rel=\"noreferrer noopener\">$285 milioni in sovvenzioni<\/a>e attualmente assegna sovvenzioni in tre aree di interesse: istruzione, salute e vitalit\u00e0 di Indianapolis.&nbsp;&nbsp;<\/p>\n<\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p><strong>Formazione scolastica<\/strong>&nbsp;<\/p>\n<\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p>Una popolazione ben istruita \u00e8 fondamentale per la vitalit\u00e0 della nostra citt\u00e0 e per la continua competitivit\u00e0 globale degli Stati Uniti. Ma a Indianapolis, troppo pochi studenti dimostrano competenza in materie accademiche fondamentali come matematica, scienze e arti inglesi\/linguistiche, e troppo pochi studenti si diplomano alla scuola superiore adeguatamente preparati per l\u2019universit\u00e0 o la carriera. Anche preoccupante \u00e8&nbsp;<a href=\"https:\/\/www.rmff.org\/insights\/research-and-reports\/education-for-all\/\" target=\"_blank\" rel=\"noreferrer noopener\">la cronica mancanza di accesso a opportunit\u00e0 educative di alta qualit\u00e0<\/a>&nbsp;affrontati dagli studenti neri e ispanici dall\u2019infanzia fino all\u2019universit\u00e0, portando a disparit\u00e0 razziali nei risultati scolastici.&nbsp;&nbsp;<\/p>\n<\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p>Migliorare&nbsp;<a href=\"https:\/\/www.rmff.org\/our-work\/education\/\" target=\"_blank\" rel=\"noreferrer noopener\">formazione scolastica<\/a>&nbsp;e i risultati della forza lavoro per tutti i bambini e gli adulti, sosteniamo iniziative che:&nbsp;<\/p>\n<\/section>\n\n<section class=\"container  block wordpress-block wordpress-list core-list\"><div class=\"row\"><div class=\"col-12\">\n<ol class=\"wp-block-list\"><li>Migliorare i risultati accademici degli studenti di Indianapolis sostenendo le condizioni necessarie per aumentare l\u2019offerta di scuole e programmi ad alte prestazioni.&nbsp;<\/li><\/ol>\n<\/div><\/div><\/section>\n\n<section class=\"container  block wordpress-block wordpress-list core-list\"><div class=\"row\"><div class=\"col-12\">\n<ol class=\"wp-block-list\" start=\"2\"><li>Ridurre al minimo la sottoccupazione e il divario di competenze della forza lavoro a Indianapolis sostenendo l\u2019erogazione di programmi di istruzione e formazione post-secondaria economicamente vantaggiosi.&nbsp;<\/li><\/ol>\n<\/div><\/div><\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p>Ad esempio, dal 2006, la Fondazione ha assegnato pi\u00f9 di $17,2 milioni a&nbsp;<a href=\"https:\/\/www.themindtrust.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">La fiducia della mente<\/a>, che funge da catalizzatore per l&#039;innovazione dell&#039;istruzione a Indianapolis. Questo finanziamento sostiene gli sforzi dell&#039;organizzazione per far crescere ottime scuole e reclutare dirigenti scolastici di qualit\u00e0, ad esempio attraverso il&nbsp;<a href=\"https:\/\/www.themindtrust.org\/relay-national-principal-academy-fellowship\/\" target=\"_blank\" rel=\"noreferrer noopener\">Borsa di studio dell&#039;Accademia nazionale dei presidi a staffetta<\/a>&nbsp;(NPAF). L&#039;NPAF forma i presidi attuali e aspiranti e i supervisori principali affinch\u00e9 diventino leader didattici e culturali, promuovendo in definitiva il successo degli studenti e aumentando il coinvolgimento della comunit\u00e0.&nbsp;<\/p>\n<\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p><strong>Salute<\/strong>&nbsp;<\/p>\n<\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p>La buona salute \u00e8 una condizione necessaria per il successo nella vita ed \u00e8 integralmente legata alla capacit\u00e0 dei bambini e degli adulti di prosperare a scuola e sul posto di lavoro. Sfortunatamente, Indianapolis si colloca in fondo o quasi in quasi tutti gli indicatori relativi alla salute pubblica e alla vita sana.&nbsp;&nbsp;<\/p>\n<\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p>Per aiutare a rivolgersi al pi\u00f9 grande pubblico di Indianapolis&nbsp;<a href=\"https:\/\/www.rmff.org\/our-work\/health\/\" target=\"_blank\" rel=\"noreferrer noopener\">salute<\/a>&nbsp;sfide, la Fondazione si \u00e8 posta gli obiettivi di:&nbsp;<\/p>\n<\/section>\n\n<section class=\"container  block wordpress-block wordpress-list core-list\"><div class=\"row\"><div class=\"col-12\">\n<ol class=\"wp-block-list\"><li>Ridurre il tasso di consumo di tabacco ed eliminare l\u2019uso di nicotina da parte dei giovani.&nbsp;<\/li><\/ol>\n<\/div><\/div><\/section>\n\n<section class=\"container  block wordpress-block wordpress-list core-list\"><div class=\"row\"><div class=\"col-12\">\n<ol class=\"wp-block-list\" start=\"2\"><li>Prevenire e affrontare il disturbo da uso di sostanze.&nbsp;<\/li><\/ol>\n<\/div><\/div><\/section>\n\n<section class=\"alignleft block wordpress-block wordpress-paragraph core-paragraph\">\n<p class=\"has-text-align-left\">Nel 2009, la Fondazione ha assegnato $20 milioni per aiutare a fondare l&#039;Universit\u00e0 dell&#039;Indiana&nbsp;<a href=\"https:\/\/fsph.iupui.edu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Scuola di sanit\u00e0 pubblica Richard M. Fairbanks<\/a>&nbsp;all&#039;IUPUI. Oggi, la Scuola prepara i leader a promuovere la salute pubblica in Indiana e oltre, sostenendo al tempo stesso la ricerca su alcune delle sfide sanitarie pi\u00f9 urgenti della nostra citt\u00e0. Con i finanziamenti della Fondazione, la Scuola ha prodotto rapporti come&nbsp;<a href=\"https:\/\/www.rmff.org\/insights\/research-and-reports\/the-opioid-epidemic-in-indiana-and-marion-county\/\" target=\"_blank\" rel=\"noreferrer noopener\">L&#039;epidemia di oppioidi in Indiana e nella contea di Marion<\/a>&nbsp;e il&nbsp;<a href=\"https:\/\/www.rmff.org\/insights\/research-and-reports\/indiana-public-health-system-review\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sistema sanitario pubblico dell&#039;Indiana<\/a>&nbsp;Revisione.&nbsp;&nbsp;<\/p>\n<\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p><strong>Vitalit\u00e0 di Indianapolis<\/strong>&nbsp;<\/p>\n<\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p>I progressi tecnologici e la globalizzazione in atto stanno rapidamente rimodellando l\u2019economia statunitense. Per rimanere competitiva quando si tratta di attrarre e trattenere datori di lavoro e talenti, l\u2019area metropolitana di Indianapolis deve continuare a concentrarsi sulla creazione di qualcosa di pi\u00f9 di ci\u00f2 che la Brookings Institution<a href=\"https:\/\/www.brookings.edu\/research\/advancing-opportunity-in-central-indiana\/\" target=\"_blank\" rel=\"noreferrer noopener\">si riferisce a \u201clavori buoni e promettenti\u201d<\/a>che sono rilevanti per il 21<sup>st<\/sup>economia del secolo. Dobbiamo allo stesso tempo garantire che le persone nell\u2019area metropolitana di Indianapolis siano pronte a ricoprire questi posti di lavoro.&nbsp;<\/p>\n<\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p>Dick Fairbanks ha creato la sua omonima Fondazione per rafforzare la vitalit\u00e0 di Indianapolis. Credeva che la Fondazione potesse realizzare questa visione sostenendo i principali fattori economici \u2013 come l\u2019attrazione dei talenti e le iniziative di sviluppo \u2013 che potrebbero contribuire a garantire che Indianapolis rimanga una citt\u00e0 fiorente.&nbsp;<\/p>\n<\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p>La Fondazione si \u00e8 posta nel ns. il seguente obiettivo&nbsp;<a href=\"https:\/\/www.rmff.org\/our-work\/vitality-of-indianapolis\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vitalit\u00e0 di Indianapolis<\/a>&nbsp;area di interesse: <\/p>\n<\/section>\n\n<section class=\"container  block wordpress-block wordpress-list core-list\"><div class=\"row\"><div class=\"col-12\">\n<ol class=\"wp-block-list\"><li>Identificare e sostenere i principali fattori economici che contribuiranno a creare una Indianapolis pi\u00f9 vivace.&nbsp;<\/li><\/ol>\n<\/div><\/div><\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p>Ad esempio, dal 2007, la Fondazione ha assegnato oltre $11 milioni a&nbsp;<a href=\"https:\/\/biocrossroads.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">BioCrocevia<\/a>, che lavora per far avanzare il settore delle scienze della vita dell&#039;Indiana attraverso collaborazioni e incontri con partner aziendali, accademici e filantropici e investimenti in startup. BioCrossroads svolge un ruolo fondamentale rafforzando il settore delle scienze della vita e sostenendo il lancio di iniziative come l\u2019Indiana Biosciences Research Institute e 16 Tech che mirano ad accelerare la crescita dei settori delle scienze della vita e dell\u2019innovazione nell\u2019Indiana centrale.&nbsp;&nbsp;<\/p>\n<\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p>Mentre celebriamo i 35 anni dalla fondazione della Richard M. Fairbanks Foundation, riflettiamo sull&#039;impatto dei nostri beneficiari e di altri partner della comunit\u00e0 che lavorano instancabilmente per migliorare la vita delle persone in Indiana. Il loro ingegno e l&#039;attenzione ai risultati di qualit\u00e0 contribuiscono a garantire che Indianapolis rimanga una citt\u00e0 fiorente che riflette la visione del nostro fondatore.&nbsp;<\/p>\n<\/section>\n\n<section class=\"block wordpress-block wordpress-paragraph core-paragraph\">\n<p><strong><em>Claire Fiddian-Green \u00e8 presidente e amministratore delegato della Richard M. Fairbanks Foundation.<\/em><\/strong>  <\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Trentacinque anni dopo la sua creazione, @RMFFIndy continua a concentrarsi sulla concessione di sovvenzioni strategiche, sulla ricerca e valutazione e sulla collaborazione intersettoriale per promuovere la vitalit\u00e0 di Indianapolis e il benessere della sua gente.\u00a0<\/p>","protected":false},"author":7,"featured_media":7892,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[30],"tags":[262,83,84],"class_list":["post-11254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-35th-anniversary","tag-richard-m-fairbanks-foundation","tag-rmff"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Celebrating Thirty-Five Years of Impact - Richard M. Fairbanks Foundation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/old.rmff.wrhosting.net\/it\/2021\/10\/celebrating-thirty-five-years-of-impact\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrating Thirty-Five Years of Impact - Richard M. Fairbanks Foundation\" \/>\n<meta property=\"og:description\" content=\"Thirty-five years after its creation, @RMFFIndy continues to focus on strategic grantmaking,\u00a0research and evaluation,\u00a0and\u00a0cross-sector collaboration to advance\u00a0the vitality of Indianapolis and the well-being of its people.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/old.rmff.wrhosting.net\/it\/2021\/10\/celebrating-thirty-five-years-of-impact\/\" \/>\n<meta property=\"og:site_name\" content=\"Richard M. Fairbanks Foundation\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-26T15:26:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-09T21:29:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/05\/Indy-Skyline-Example.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RMFF Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"RMFF Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/\",\"url\":\"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/\",\"name\":\"Celebrating Thirty-Five Years of Impact - Richard M. Fairbanks Foundation\",\"isPartOf\":{\"@id\":\"https:\/\/old.rmff.wrhosting.net\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/05\/Indy-Skyline-Example.jpg\",\"datePublished\":\"2021-10-26T15:26:37+00:00\",\"dateModified\":\"2022-03-09T21:29:08+00:00\",\"author\":{\"@id\":\"https:\/\/old.rmff.wrhosting.net\/#\/schema\/person\/b9b457f46976a7df932bc8f5cd932a2b\"},\"breadcrumb\":{\"@id\":\"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/#primaryimage\",\"url\":\"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/05\/Indy-Skyline-Example.jpg\",\"contentUrl\":\"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/05\/Indy-Skyline-Example.jpg\",\"width\":1200,\"height\":801},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/old.rmff.wrhosting.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebrating Thirty-Five Years of Impact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/old.rmff.wrhosting.net\/#website\",\"url\":\"https:\/\/old.rmff.wrhosting.net\/\",\"name\":\"Richard M. Fairbanks Foundation\",\"description\":\"Advancing the vitality of Indianapolis and the well-being of its people.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/old.rmff.wrhosting.net\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/old.rmff.wrhosting.net\/#\/schema\/person\/b9b457f46976a7df932bc8f5cd932a2b\",\"name\":\"RMFF Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/old.rmff.wrhosting.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/12c7a6f2976d144ddd06770e26358ad375903bd67a5780c9e3f58914c92511a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/12c7a6f2976d144ddd06770e26358ad375903bd67a5780c9e3f58914c92511a7?s=96&d=mm&r=g\",\"caption\":\"RMFF Staff\"},\"url\":\"https:\/\/old.rmff.wrhosting.net\/it\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebrating Thirty-Five Years of Impact - Richard M. Fairbanks Foundation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/old.rmff.wrhosting.net\/it\/2021\/10\/celebrating-thirty-five-years-of-impact\/","og_locale":"it_IT","og_type":"article","og_title":"Celebrating Thirty-Five Years of Impact - Richard M. Fairbanks Foundation","og_description":"Thirty-five years after its creation, @RMFFIndy continues to focus on strategic grantmaking,\u00a0research and evaluation,\u00a0and\u00a0cross-sector collaboration to advance\u00a0the vitality of Indianapolis and the well-being of its people.\u00a0","og_url":"https:\/\/old.rmff.wrhosting.net\/it\/2021\/10\/celebrating-thirty-five-years-of-impact\/","og_site_name":"Richard M. Fairbanks Foundation","article_published_time":"2021-10-26T15:26:37+00:00","article_modified_time":"2022-03-09T21:29:08+00:00","og_image":[{"width":1200,"height":801,"url":"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/05\/Indy-Skyline-Example.jpg","type":"image\/jpeg"}],"author":"RMFF Staff","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"RMFF Staff","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/","url":"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/","name":"Celebrating Thirty-Five Years of Impact - Richard M. Fairbanks Foundation","isPartOf":{"@id":"https:\/\/old.rmff.wrhosting.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/#primaryimage"},"image":{"@id":"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/#primaryimage"},"thumbnailUrl":"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/05\/Indy-Skyline-Example.jpg","datePublished":"2021-10-26T15:26:37+00:00","dateModified":"2022-03-09T21:29:08+00:00","author":{"@id":"https:\/\/old.rmff.wrhosting.net\/#\/schema\/person\/b9b457f46976a7df932bc8f5cd932a2b"},"breadcrumb":{"@id":"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/#primaryimage","url":"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/05\/Indy-Skyline-Example.jpg","contentUrl":"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/05\/Indy-Skyline-Example.jpg","width":1200,"height":801},{"@type":"BreadcrumbList","@id":"https:\/\/old.rmff.wrhosting.net\/ar\/2021\/10\/celebrating-thirty-five-years-of-impact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/old.rmff.wrhosting.net\/"},{"@type":"ListItem","position":2,"name":"Celebrating Thirty-Five Years of Impact"}]},{"@type":"WebSite","@id":"https:\/\/old.rmff.wrhosting.net\/#website","url":"https:\/\/old.rmff.wrhosting.net\/","name":"Fondazione Richard M. Fairbanks","description":"Promuovere la vitalit\u00e0 di Indianapolis e il benessere della sua gente.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/old.rmff.wrhosting.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/old.rmff.wrhosting.net\/#\/schema\/person\/b9b457f46976a7df932bc8f5cd932a2b","name":"RMFF Staff","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/old.rmff.wrhosting.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/12c7a6f2976d144ddd06770e26358ad375903bd67a5780c9e3f58914c92511a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12c7a6f2976d144ddd06770e26358ad375903bd67a5780c9e3f58914c92511a7?s=96&d=mm&r=g","caption":"RMFF Staff"},"url":"https:\/\/old.rmff.wrhosting.net\/it\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/old.rmff.wrhosting.net\/it\/wp-json\/wp\/v2\/posts\/11254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/old.rmff.wrhosting.net\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/old.rmff.wrhosting.net\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/old.rmff.wrhosting.net\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/old.rmff.wrhosting.net\/it\/wp-json\/wp\/v2\/comments?post=11254"}],"version-history":[{"count":9,"href":"https:\/\/old.rmff.wrhosting.net\/it\/wp-json\/wp\/v2\/posts\/11254\/revisions"}],"predecessor-version":[{"id":11633,"href":"https:\/\/old.rmff.wrhosting.net\/it\/wp-json\/wp\/v2\/posts\/11254\/revisions\/11633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/old.rmff.wrhosting.net\/it\/wp-json\/wp\/v2\/media\/7892"}],"wp:attachment":[{"href":"https:\/\/old.rmff.wrhosting.net\/it\/wp-json\/wp\/v2\/media?parent=11254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/old.rmff.wrhosting.net\/it\/wp-json\/wp\/v2\/categories?post=11254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/old.rmff.wrhosting.net\/it\/wp-json\/wp\/v2\/tags?post=11254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}