{"id":944,"date":"2021-04-13T15:03:21","date_gmt":"2021-04-13T15:03:21","guid":{"rendered":"https:\/\/www.rmff.org\/?page_id=944"},"modified":"2024-10-10T14:57:27","modified_gmt":"2024-10-10T18:57:27","slug":"community-data-snapshot","status":"publish","type":"page","link":"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/","title":{"rendered":"Resumen de datos de la comunidad"},"content":{"rendered":"<section id=\"header-with-content-overlay-block_d8d3ca2e90646da2abe51bbb9d4c0ef9\"\n  class=\"block header-with-content-overlay-wrapper small-heading\"\n  style=\"background-image: -webkit-linear-gradient(top, rgba(0,0,0,0) 60%, rgba(0,0,0,0.7)), url('https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/05\/getty-images-901369874@2x.jpg')\">\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-12\">\n        <div class=\"heading-wrapper\">\n          <h1>UNA INSTANT\u00c1NEA DE LOS INDICADORES CLAVE DE LA COMUNIDAD<\/h1>\n                  <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<section id=\"two-column-color-call-to-action-block_f43c76cc047064cff21e2051a53aea5f\" class=\"block two-column-color-call-to-action-wrapper\">\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-12\">\n        <div class=\"content-wrapper\">\n          <div class=\"left-content\">\n            <div class=\"content\">\n              <p>La instant\u00e1nea de datos de la comunidad contiene m\u00e1s de <strong style=\"color: #0c3842\">200 gr\u00e1ficos<\/strong> que incluyen datos sobre indicadores clave en nuestras \u00e1reas de enfoque. <strong style=\"color: #0c3842\">Haga clic en los iconos a continuaci\u00f3n para explorar<strong>.<\/p>\n            <\/div>\n                      <\/div>\n          <div class=\"right-content\">\n                          <div class=\"right-inner-content\">\n                <div class=\"text-1\">\n                  <p>comunidad<\/p>\n                <\/div>\n                <div class=\"text-2\">\n                  <p>datos<\/p>\n                <\/div>\n                <div class=\"text-3\">\n                  <p>INSTANT\u00c1NEA<\/p>\n                <\/div>\n              <\/div>\n                        <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<section id=\"center-heading-with-subtitle-block_73ef0db0d1beb0eb465206e55e454355\" class=\"block center-heading-with-subtitle-wrapper\">\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-12\">\n        <div class=\"heading-wrapper\">\n                      <h2>\u2014 Datos que estamos rastreando \u2014<\/h2>\n                    <\/div>\n        <div class=\"subtitle-wrapper\">\n          <p style=\"text-align: center;\">Para medir el bienestar de la comunidad en nuestras \u00e1reas de enfoque principales, recopilamos datos de una variedad de fuentes y los publicamos en nuestro Resumen de datos de la comunidad, actualizando nueva informaci\u00f3n a medida que est\u00e9 disponible. En la mayor\u00eda de los casos, los datos comienzan en 2010, con algunas excepciones debido a la disponibilidad limitada. Siempre que fue posible, los datos se han desglosado por edad, g\u00e9nero, ingresos, raza y origen \u00e9tnico.<\/p>\n<p style=\"text-align: center;\">\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Invitamos a nuestros beneficiarios y otros socios comunitarios a descargar esta informaci\u00f3n para informar su trabajo. Tenga en cuenta que, si bien hacemos todo lo posible para confirmar que todos los datos sean correctos, debido a que los datos provienen de una variedad de fuentes, no podemos garantizar su exactitud.<\/p>\n<p style=\"text-align: center;\">\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">\u00bfPreguntas o inquietudes? Env\u00edanos un email a <a href=\"mailto:CommunityDataSnapshot@RMFF.org\">CommunityDataSnapshot@RMFF.org<\/a>.<\/p>\n<p style=\"text-align: center;\">\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: center;\"><strong style=\"color: #2ebbab;\">Haga clic en los \u00edconos a continuaci\u00f3n para explorar datos en nuestras \u00e1reas de enfoque principales.<\/strong><\/h4>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<section id=\"four-column-image-with-content-block_f5d90840c295e1a88fdbe65a7d964c59\"\n  class=\"block four-column-image-with-content-wrapper\">\n  <div class=\"container\">\n    <div class=\"row\">\n                        <div class=\"col-12 col-md-3\">\n                <a class=\"not-active\" href=\"https:\/\/www.rmff.org\/community-data-snapshot\/education\/\"\n          title=\"Educaci\u00f3n\" target=\"\">\n                    <div class=\"single-content\">\n                        <div class=\"heading-wrapper\">\n              <h3 class=\"\">EDUCACI\u00d3N<\/h3>\n            <\/div>\n                                    <div class=\"icon-wrapper\">\n              <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/04\/icon-education.png\" alt=\"\" \/>\n            <\/div>\n                                    <div class=\"content-wrapper\">\n              <p class=\"\">Explore datos educativos clave<\/p>\n            <\/div>\n                      <\/div>\n                  <\/a>\n              <\/div>\n                  <div class=\"col-12 col-md-3\">\n                <a class=\"not-active\" href=\"https:\/\/www.rmff.org\/community-data-snapshot\/health\/\"\n          title=\"Salud\" target=\"\">\n                    <div class=\"single-content\">\n                        <div class=\"heading-wrapper\">\n              <h3 class=\"\">SALUD<\/h3>\n            <\/div>\n                                    <div class=\"icon-wrapper\">\n              <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/04\/icon-health.png\" alt=\"\" \/>\n            <\/div>\n                                    <div class=\"content-wrapper\">\n              <p class=\"\">Explore datos de salud clave<\/p>\n            <\/div>\n                      <\/div>\n                  <\/a>\n              <\/div>\n                  <div class=\"col-12 col-md-3\">\n                <a class=\"not-active\" href=\"https:\/\/www.rmff.org\/community-data-snapshot\/vitality-of-indianapolis\/\"\n          title=\"Vitalidad de Indian\u00e1polis\" target=\"\">\n                    <div class=\"single-content\">\n                        <div class=\"heading-wrapper\">\n              <h3 class=\"\">VITALIDAD<\/h3>\n            <\/div>\n                                    <div class=\"icon-wrapper\">\n              <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/04\/icon-vitality.png\" alt=\"\" \/>\n            <\/div>\n                                    <div class=\"content-wrapper\">\n              <p class=\"\">Explore la vitalidad clave de los datos de Indian\u00e1polis<\/p>\n            <\/div>\n                      <\/div>\n                  <\/a>\n              <\/div>\n                  <div class=\"col-12 col-md-3\">\n                <a class=\"not-active\" href=\"https:\/\/www.rmff.org\/community-data-snapshot\/demographics\/\"\n          title=\"Demograf\u00eda\" target=\"\">\n                    <div class=\"single-content\">\n                        <div class=\"heading-wrapper\">\n              <h3 class=\"\">DEMOGRAFIA<\/h3>\n            <\/div>\n                                    <div class=\"icon-wrapper\">\n              <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/04\/icon-demographics.png\" alt=\"\" \/>\n            <\/div>\n                                    <div class=\"content-wrapper\">\n              <p class=\"\">Explora datos demogr\u00e1ficos clave<\/p>\n            <\/div>\n                      <\/div>\n                  <\/a>\n              <\/div>\n                <\/div>\n  <\/div>\n<\/section>\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<section id=\"card-call-to-action-block_131a3f2274e088aa871761a3f09ca8b1\" class=\"block card-call-to-action-wrapper\">\n  <div class=\"container\">\n    <div class=\"row\">\n                                    <div\n        class=\"col-12 col-lg-7 col-spacer\">\n        <div class=\"single-card-wrapper\">\n          <div class=\"image-wrapper\">\n                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2021\/12\/CDS_Education_Graphic-575x300.jpg\" alt=\"\" \/>\n                      <\/div>\n          <div class=\"card-content-wrapper\">\n            <div class=\"inner-content\">\n              <div class=\"large-heading-wrapper\">\n                <h2>36.5%<\/h2>\n              <\/div>\n              <div class=\"heading-wrapper\">\n                <h3>Only 36.5% of Marion County adults have a bachelor\u2019s degree or higher.<\/h3>\n              <\/div>\n              <div class=\"content-wrapper\">\n                <p>Only 26.1% of Black adults and 21.3% of Hispanic\/Latino adults have a college degree.<\/p>\n              <\/div>\n              <div class=\"card-button-wrapper\">\n                <a class=\"default-button\" href=\"https:\/\/www.rmff.org\/community-data-snapshot\/education\/\" title=\"Aprende m\u00e1s\"\n                  target=\"\">Aprende m\u00e1s<\/a>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n                                          <div\n        class=\"col-12 col-lg-5 col-spacer\">\n        <div class=\"single-card-wrapper\">\n          <div class=\"image-wrapper\">\n                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2022\/11\/image-drugs@2x-385x300.jpg\" alt=\"\" \/>\n                      <\/div>\n          <div class=\"card-content-wrapper\">\n            <div class=\"inner-content\">\n              <div class=\"large-heading-wrapper\">\n                <h2>86%<\/h2>\n              <\/div>\n              <div class=\"heading-wrapper\">\n                <h3>El fentanilo fue un factor en el 86% de muertes inducidas por drogas (sobredosis).<\/h3>\n              <\/div>\n              <div class=\"content-wrapper\">\n                <p>En 492 de las 682 sobredosis mortales ocurridas en 2022, estuvo implicada m\u00e1s de una sustancia.<\/p>\n              <\/div>\n              <div class=\"card-button-wrapper\">\n                <a class=\"default-button\" href=\"https:\/\/www.rmff.org\/community-data-snapshot\/health\/\" title=\"Aprende m\u00e1s\"\n                  target=\"\">Aprende m\u00e1s<\/a>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n                            <\/div>\n  <\/div>\n<\/section>\n\n<section id=\"card-call-to-action-block_1d0268f1b5b0fe61ae15360bf79bfb63\" class=\"block card-call-to-action-wrapper\">\n  <div class=\"container\">\n    <div class=\"row\">\n                              <div class=\"col-12 col-lg-4 col-spacer three-column-layout\">\n        <div class=\"single-card-wrapper\">\n          <div class=\"image-wrapper\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2022\/11\/image-rent@2x-290x300.jpg\" alt=\"\" \/>\n          <\/div>\n          <div class=\"card-content-wrapper\">\n            <div class=\"inner-content\">\n              <div class=\"large-heading-wrapper\">\n                <h2>49.5%<\/h2>\n              <\/div>\n              <div class=\"heading-wrapper\">\n                <h3>In 2023, 49.5% of Marion County\u2019s renters spent at least 30% of their household income on rent.<\/h3>\n              <\/div>\n              <div class=\"content-wrapper\">\n                <p>25.5% spent at least half of their household income on rent.<\/p>\n              <\/div>\n              <div class=\"card-button-wrapper\">\n                <a class=\"default-button\" href=\"https:\/\/www.rmff.org\/community-data-snapshot\/vitality-of-indianapolis\/\" title=\"Aprende m\u00e1s\"\n                  target=\"\">Aprende m\u00e1s<\/a>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n                              <div class=\"col-12 col-lg-4 col-spacer three-column-layout\">\n        <div class=\"single-card-wrapper\">\n          <div class=\"image-wrapper\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2022\/11\/image-from-current-site@2x-290x300.jpg\" alt=\"\" \/>\n          <\/div>\n          <div class=\"card-content-wrapper\">\n            <div class=\"inner-content\">\n              <div class=\"large-heading-wrapper\">\n                <h2>1 de cada 6<\/h2>\n              <\/div>\n              <div class=\"heading-wrapper\">\n                <h3>En 2022, 17% de estudiantes de 12.\u00ba grado del condado de Marion informaron haber usado cigarrillos electr\u00f3nicos (vapear).<\/h3>\n              <\/div>\n              <div class=\"content-wrapper\">\n                <p><\/p>\n              <\/div>\n              <div class=\"card-button-wrapper\">\n                <a class=\"default-button\" href=\"https:\/\/www.rmff.org\/community-data-snapshot\/health\/\" title=\"Aprende m\u00e1s\"\n                  target=\"\">Aprende m\u00e1s<\/a>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n                              <div class=\"col-12 col-lg-4 col-spacer three-column-layout\">\n        <div class=\"single-card-wrapper\">\n          <div class=\"image-wrapper\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/old.rmff.wrhosting.net\/wp-content\/uploads\/2022\/11\/image-vote@2x-290x300.jpg\" alt=\"\" \/>\n          <\/div>\n          <div class=\"card-content-wrapper\">\n            <div class=\"inner-content\">\n              <div class=\"large-heading-wrapper\">\n                <h2>59%<\/h2>\n              <\/div>\n              <div class=\"heading-wrapper\">\n                <h3>La tasa de participaci\u00f3n de votantes del condado de Marion para las elecciones generales de 2020 fue de 59%.<\/h3>\n              <\/div>\n              <div class=\"content-wrapper\">\n                <p>Esto es 6 puntos porcentuales m\u00e1s que en 2016.<\/p>\n              <\/div>\n              <div class=\"card-button-wrapper\">\n                <a class=\"default-button\" href=\"https:\/\/www.rmff.org\/community-data-snapshot\/vitality-of-indianapolis\/\" title=\"Aprende m\u00e1s\"\n                  target=\"\">Aprende m\u00e1s<\/a>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n                      <\/div>\n  <\/div>\n<\/section>\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>\nlabel {\n  color: white;\n}\n<\/style>\n\n<section id=\"newsletter-signup-block_086df1143399666e78acc31b6861f2da\" class=\"newsletter-signup-wrapper-new\">\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-12 col-lg-5\">\n        <div class=\"signup-content-wrapper\">\n          <div class=\"headline-content\">\n            <h2>Suscr\u00edbete a nuestro bolet\u00edn<\/h2>\n          <\/div>\n          <div class=\"signup-content\">\n            <p>Reciba actualizaciones de la Fundaci\u00f3n directamente en su bandeja de entrada.<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"col-12 col-lg-7\">\n        <div class=\"signup-form-wrapper\">\n          <div class=\"signup-form\">\n            <link rel='stylesheet' id='formidable-css' defer href='https:\/\/old.rmff.wrhosting.net\/wp-content\/plugins\/formidable\/css\/formidableforms.css' type='text\/css' media='all' \/>\n<div class=\"frm_forms  with_frm_style frm_style_formidable-style\" id=\"frm_form_8_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form\" id=\"form_newslettersignupnew\" action=\"\" >\n<div class=\"frm_form_fields\">\n<fieldset>\n<legend class=\"frm_screen_reader\">Suscr\u00edbete al bolet\u00edn NUEVO<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"8\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_8\" id=\"frm_hide_fields_8\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"newslettersignupnew\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_8\" name=\"frm_submit_entry_8\" value=\"5d8e6aa20b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/944\" \/><div id=\"frm_field_39_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container frm6 frm_first\">\r\n    <label for=\"field_bn3oh22\" id=\"field_bn3oh22_label\" class=\"frm_primary_label\">Nombre de pila\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_bn3oh22\" name=\"item_meta[39]\" value=\"\"  placeholder=\"Nombre de pila *\" data-reqmsg=\"First Name cannot be blank.\" aria-required=\"true\" data-invmsg=\"Text is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_40_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container frm6\">\r\n    <label for=\"field_qe1zv\" id=\"field_qe1zv_label\" class=\"frm_primary_label\">Apellido\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_qe1zv\" name=\"item_meta[40]\" value=\"\"  placeholder=\"Apellido *\" data-reqmsg=\"Last Name cannot be blank.\" aria-required=\"true\" data-invmsg=\"Text is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_41_container\" class=\"frm_form_field form-field  frm_required_field frm_hidden_container frm12 frm_first\">\r\n    <label for=\"field_scto522\" id=\"field_scto522_label\" class=\"frm_primary_label\">Correo electr\u00f3nico\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_scto522\" name=\"item_meta[41]\" value=\"\"  placeholder=\"Correo electr\u00f3nico *\" data-reqmsg=\"Email cannot be blank.\" aria-required=\"true\" data-invmsg=\"Email is invalid\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_42_container\" class=\"frm_form_field form-field  frm_none_container frm6 frm_first\">\r\n    <label for=\"field_lx3lq\" id=\"field_lx3lq_label\" class=\"frm_primary_label\">T\u00edtulo profesional\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_lx3lq\" name=\"item_meta[42]\" value=\"\"  placeholder=\"T\u00edtulo profesional\" data-invmsg=\"Text is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_43_container\" class=\"frm_form_field form-field  frm_none_container frm6\">\r\n    <label for=\"field_8xhsu\" id=\"field_8xhsu_label\" class=\"frm_primary_label\">Organizaci\u00f3n\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_8xhsu\" name=\"item_meta[43]\" value=\"\"  placeholder=\"Organizaci\u00f3n\" data-invmsg=\"Text is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_53_container\" class=\"frm_form_field form-field\">\r\n\t<div class=\"frm_submit\" style=\"text-align: right;\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">INSCRIBIRSE<\/button>\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_67_container\">\n\t\t\t<label for=\"field_w1tnh\" >\n\t\t\t\tSi eres humano, deja este campo en blanco.\t\t\t<\/label>\n\t\t\t<input  id=\"field_w1tnh\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[67]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"5zNPxgsYxU\/\/FZjACs3Ayxt36iLWmpv+TbzXHe1Vwpw31\/Gx91bxAzUfsmYbI12y\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":50,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-944","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Community Data Snapshot - Richard M. Fairbanks Foundation<\/title>\n<meta name=\"description\" content=\"The Richard M. Fairbanks Foundation regularly collects data on key indicators across our focus areas to inform our work. We are pleased to present this information to you in our Community Data Snapshot.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Community Data Snapshot - Richard M. Fairbanks Foundation\" \/>\n<meta property=\"og:description\" content=\"The Richard M. Fairbanks Foundation regularly collects data on key indicators across our focus areas to inform our work. We are pleased to present this information to you in our Community Data Snapshot.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/\" \/>\n<meta property=\"og:site_name\" content=\"Richard M. Fairbanks Foundation\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-10T18:57:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/\",\"url\":\"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/\",\"name\":\"Community Data Snapshot - Richard M. Fairbanks Foundation\",\"isPartOf\":{\"@id\":\"https:\/\/old.rmff.wrhosting.net\/#website\"},\"datePublished\":\"2021-04-13T15:03:21+00:00\",\"dateModified\":\"2024-10-10T18:57:27+00:00\",\"description\":\"The Richard M. Fairbanks Foundation regularly collects data on key indicators across our focus areas to inform our work. We are pleased to present this information to you in our Community Data Snapshot.\",\"breadcrumb\":{\"@id\":\"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/old.rmff.wrhosting.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Community Data Snapshot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/old.rmff.wrhosting.net\/#website\",\"url\":\"https:\/\/old.rmff.wrhosting.net\/\",\"name\":\"Richard M. Fairbanks Foundation\",\"description\":\"Advancing the vitality of Indianapolis and the well-being of its people.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/old.rmff.wrhosting.net\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Community Data Snapshot - Richard M. Fairbanks Foundation","description":"The Richard M. Fairbanks Foundation regularly collects data on key indicators across our focus areas to inform our work. We are pleased to present this information to you in our Community Data Snapshot.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/","og_locale":"es_ES","og_type":"article","og_title":"Community Data Snapshot - Richard M. Fairbanks Foundation","og_description":"The Richard M. Fairbanks Foundation regularly collects data on key indicators across our focus areas to inform our work. We are pleased to present this information to you in our Community Data Snapshot.","og_url":"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/","og_site_name":"Richard M. Fairbanks Foundation","article_modified_time":"2024-10-10T18:57:27+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/","url":"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/","name":"Community Data Snapshot - Richard M. Fairbanks Foundation","isPartOf":{"@id":"https:\/\/old.rmff.wrhosting.net\/#website"},"datePublished":"2021-04-13T15:03:21+00:00","dateModified":"2024-10-10T18:57:27+00:00","description":"The Richard M. Fairbanks Foundation regularly collects data on key indicators across our focus areas to inform our work. We are pleased to present this information to you in our Community Data Snapshot.","breadcrumb":{"@id":"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/old.rmff.wrhosting.net\/es\/community-data-snapshot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/old.rmff.wrhosting.net\/"},{"@type":"ListItem","position":2,"name":"Community Data Snapshot"}]},{"@type":"WebSite","@id":"https:\/\/old.rmff.wrhosting.net\/#website","url":"https:\/\/old.rmff.wrhosting.net\/","name":"Fundaci\u00f3n Richard M. Fairbanks","description":"Promover la vitalidad de Indian\u00e1polis y el bienestar de su gente.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/old.rmff.wrhosting.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/old.rmff.wrhosting.net\/es\/wp-json\/wp\/v2\/pages\/944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/old.rmff.wrhosting.net\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/old.rmff.wrhosting.net\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/old.rmff.wrhosting.net\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/old.rmff.wrhosting.net\/es\/wp-json\/wp\/v2\/comments?post=944"}],"version-history":[{"count":42,"href":"https:\/\/old.rmff.wrhosting.net\/es\/wp-json\/wp\/v2\/pages\/944\/revisions"}],"predecessor-version":[{"id":14531,"href":"https:\/\/old.rmff.wrhosting.net\/es\/wp-json\/wp\/v2\/pages\/944\/revisions\/14531"}],"wp:attachment":[{"href":"https:\/\/old.rmff.wrhosting.net\/es\/wp-json\/wp\/v2\/media?parent=944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}